{"id":5761,"date":"2021-09-06T11:07:39","date_gmt":"2021-09-06T10:07:39","guid":{"rendered":"https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/"},"modified":"2021-09-06T11:07:39","modified_gmt":"2021-09-06T10:07:39","slug":"healing-workshop-45","status":"publish","type":"legacy_course","link":"https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/","title":{"rendered":"Healing Workshop"},"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","legacy_course_code":"08HWS02EG","legacy_course_location":"672","legacy_course_start_date":"2008-04-10","legacy_course_end_date":"2008-04-13"},"class_list":["post-5761","legacy_course","type-legacy_course","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Healing Workshop - Ellel UK Courses<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Healing Workshop - Ellel UK Courses\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/\" \/>\n<meta property=\"og:site_name\" content=\"Ellel UK Courses\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ellel.uk\\\/courses\\\/legacy_course\\\/healing-workshop-45\\\/\",\"url\":\"https:\\\/\\\/ellel.uk\\\/courses\\\/legacy_course\\\/healing-workshop-45\\\/\",\"name\":\"Healing Workshop - Ellel UK Courses\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ellel.uk\\\/courses\\\/#website\"},\"datePublished\":\"2021-09-06T10:07:39+00:00\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ellel.uk\\\/courses\\\/legacy_course\\\/healing-workshop-45\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ellel.uk\\\/courses\\\/#website\",\"url\":\"https:\\\/\\\/ellel.uk\\\/courses\\\/\",\"name\":\"Ellel UK Courses\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ellel.uk\\\/courses\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Healing Workshop - Ellel UK Courses","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/","og_locale":"en_GB","og_type":"article","og_title":"Healing Workshop - Ellel UK Courses","og_url":"https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/","og_site_name":"Ellel UK Courses","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/","url":"https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/","name":"Healing Workshop - Ellel UK Courses","isPartOf":{"@id":"https:\/\/ellel.uk\/courses\/#website"},"datePublished":"2021-09-06T10:07:39+00:00","inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ellel.uk\/courses\/legacy_course\/healing-workshop-45\/"]}]},{"@type":"WebSite","@id":"https:\/\/ellel.uk\/courses\/#website","url":"https:\/\/ellel.uk\/courses\/","name":"Ellel UK Courses","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ellel.uk\/courses\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/ellel.uk\/courses\/wp-json\/wp\/v2\/legacy_course\/5761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ellel.uk\/courses\/wp-json\/wp\/v2\/legacy_course"}],"about":[{"href":"https:\/\/ellel.uk\/courses\/wp-json\/wp\/v2\/types\/legacy_course"}],"wp:attachment":[{"href":"https:\/\/ellel.uk\/courses\/wp-json\/wp\/v2\/media?parent=5761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}